{"id":888,"date":"2020-10-24T19:15:51","date_gmt":"2020-10-24T17:15:51","guid":{"rendered":"http:\/\/hapetho.de\/gschwandnergasse42\/?p=888"},"modified":"2020-10-24T19:22:35","modified_gmt":"2020-10-24T17:22:35","slug":"meine-verbindung-mit-wedel","status":"publish","type":"post","link":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/2020\/10\/24\/meine-verbindung-mit-wedel\/","title":{"rendered":"&#8230;. meine Verbindung mit Wedel"},"content":{"rendered":"<p>Dlschad, unser syrischer Asylbewerber, den Hannelore und ich<br \/>\nin Wedel betreuen hat jetzt wieder ein smartphone. Die einzige<br \/>\nM\u00f6glichkeit Kontaskt mit ihm zu haben. Sein altes smartphone<br \/>\nwar kaputtgegangen. DAnk der Grossherzigkeit von Nachbarn hat<br \/>\ner jetzt ein altes,leistungsf\u00e4higes\u00a0 \u00a0geschenkt bekommen. Danke<br \/>\nDlschad macht unseren Garten und h\u00fctet das Haus in Wedel.<br \/>\nIch habe jetzt wieder Kontakt mit ihm<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-877\" src=\"http:\/\/hapetho.de\/gschwandnergasse42\/wp-content\/uploads\/2020\/10\/dlschad_490-300x300.jpg\" alt=\"\" width=\"443\" height=\"443\" srcset=\"http:\/\/hapetho.de\/gschwandnergasse42\/wp-content\/uploads\/2020\/10\/dlschad_490-300x300.jpg 300w, http:\/\/hapetho.de\/gschwandnergasse42\/wp-content\/uploads\/2020\/10\/dlschad_490-150x150.jpg 150w, http:\/\/hapetho.de\/gschwandnergasse42\/wp-content\/uploads\/2020\/10\/dlschad_490.jpg 490w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dlschad, unser syrischer Asylbewerber, den Hannelore und ich in Wedel betreuen hat jetzt wieder ein smartphone. Die einzige M\u00f6glichkeit Kontaskt mit ihm zu haben. Sein altes smartphone war kaputtgegangen. DAnk der Grossherzigkeit von Nachbarn hat er jetzt ein altes,leistungsf\u00e4higes\u00a0 \u00a0geschenkt bekommen. Danke Dlschad macht unseren Garten und h\u00fctet das Haus in Wedel. Ich habe jetzt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/posts\/888"}],"collection":[{"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":2,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":893,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/posts\/888\/revisions\/893"}],"wp:attachment":[{"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hapetho.de\/gschwandnergasse42\/index.php\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}